{"id":11,"date":"2016-07-20T15:10:24","date_gmt":"2016-07-20T13:10:24","guid":{"rendered":"https:\/\/nantocleantech.us\/area51\/?p=11"},"modified":"2018-09-17T16:40:36","modified_gmt":"2018-09-17T14:40:36","slug":"empresa","status":"publish","type":"post","link":"https:\/\/nantocleantech.us\/es\/empresa\/","title":{"rendered":"EMPRESA"},"content":{"rendered":"<p>Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones los mercados de oil&amp;gas, industria pesada, infraestructuras, transportes, marine, etc<\/p>\n<p>Los portfolios de patentes representan el resultado de m\u00e1s de diez anos de investigaci\u00f3n cient\u00edfica, desarrollo y dise\u00f1o. La empresa se empe\u00f1a en transferir y en integrar sus resultados innovadores en las soluciones \u00abcleantech\u00bb adecuadas para satisfacer las esigencias de los clientes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-11","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-about-us"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"nantocleantech\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/nantocleantech.us\/es\/empresa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nanto Cleantech - Singularity Materials\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"EMPRESA - Nanto Cleantech\" \/>\n\t\t<meta property=\"og:description\" content=\"Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nantocleantech.us\/es\/empresa\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-07-20T13:10:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-09-17T14:40:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"EMPRESA - Nanto Cleantech\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#blogposting\",\"name\":\"EMPRESA - Nanto Cleantech\",\"headline\":\"EMPRESA\",\"author\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/author\\\/nantocleantech\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nantocleantech.us\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/company-overview.jpg\",\"width\":750,\"height\":260},\"datePublished\":\"2016-07-20T15:10:24+02:00\",\"dateModified\":\"2018-09-17T16:40:36+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#webpage\"},\"articleSection\":\"About us\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nantocleantech.us\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/category\\\/about-us\\\/#listItem\",\"name\":\"About us\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/category\\\/about-us\\\/#listItem\",\"position\":2,\"name\":\"About us\",\"item\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/category\\\/about-us\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#listItem\",\"name\":\"EMPRESA\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#listItem\",\"position\":3,\"name\":\"EMPRESA\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/category\\\/about-us\\\/#listItem\",\"name\":\"About us\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/#organization\",\"name\":\"Nanto Cleantech\",\"description\":\"Singularity Materials\",\"url\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/author\\\/nantocleantech\\\/#author\",\"url\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/author\\\/nantocleantech\\\/\",\"name\":\"nantocleantech\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d89d1a5e1a09088376fd7f662e559c8ab3bc854d0ee9845e892cebd5844c324d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"nantocleantech\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#webpage\",\"url\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/\",\"name\":\"EMPRESA - Nanto Cleantech\",\"description\":\"Nanto Cleantech es una empresa orientada hacia la innovaci\\u00f3n, que posee el know-how, las patentes y las tecnolog\\u00edas para realizar materiales avanzados de nueva generaci\\u00f3n (anti-corrosi\\u00f3n, flame\\\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/author\\\/nantocleantech\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/author\\\/nantocleantech\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nantocleantech.us\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/company-overview.jpg\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#mainImage\",\"width\":750,\"height\":260},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/empresa\\\/#mainImage\"},\"datePublished\":\"2016-07-20T15:10:24+02:00\",\"dateModified\":\"2018-09-17T16:40:36+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/\",\"name\":\"Nanto Cleantech\",\"description\":\"Singularity Materials\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/nantocleantech.us\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"EMPRESA - Nanto Cleantech","description":"Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones","canonical_url":"https:\/\/nantocleantech.us\/es\/empresa\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/nantocleantech.us\/es\/empresa\/#blogposting","name":"EMPRESA - Nanto Cleantech","headline":"EMPRESA","author":{"@id":"https:\/\/nantocleantech.us\/es\/author\/nantocleantech\/#author"},"publisher":{"@id":"https:\/\/nantocleantech.us\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/nantocleantech.us\/wp-content\/uploads\/2016\/07\/company-overview.jpg","width":750,"height":260},"datePublished":"2016-07-20T15:10:24+02:00","dateModified":"2018-09-17T16:40:36+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/nantocleantech.us\/es\/empresa\/#webpage"},"isPartOf":{"@id":"https:\/\/nantocleantech.us\/es\/empresa\/#webpage"},"articleSection":"About us"},{"@type":"BreadcrumbList","@id":"https:\/\/nantocleantech.us\/es\/empresa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nantocleantech.us\/es#listItem","position":1,"name":"Home","item":"https:\/\/nantocleantech.us\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/nantocleantech.us\/es\/category\/about-us\/#listItem","name":"About us"}},{"@type":"ListItem","@id":"https:\/\/nantocleantech.us\/es\/category\/about-us\/#listItem","position":2,"name":"About us","item":"https:\/\/nantocleantech.us\/es\/category\/about-us\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nantocleantech.us\/es\/empresa\/#listItem","name":"EMPRESA"},"previousItem":{"@type":"ListItem","@id":"https:\/\/nantocleantech.us\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/nantocleantech.us\/es\/empresa\/#listItem","position":3,"name":"EMPRESA","previousItem":{"@type":"ListItem","@id":"https:\/\/nantocleantech.us\/es\/category\/about-us\/#listItem","name":"About us"}}]},{"@type":"Organization","@id":"https:\/\/nantocleantech.us\/es\/#organization","name":"Nanto Cleantech","description":"Singularity Materials","url":"https:\/\/nantocleantech.us\/es\/"},{"@type":"Person","@id":"https:\/\/nantocleantech.us\/es\/author\/nantocleantech\/#author","url":"https:\/\/nantocleantech.us\/es\/author\/nantocleantech\/","name":"nantocleantech","image":{"@type":"ImageObject","@id":"https:\/\/nantocleantech.us\/es\/empresa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d89d1a5e1a09088376fd7f662e559c8ab3bc854d0ee9845e892cebd5844c324d?s=96&d=mm&r=g","width":96,"height":96,"caption":"nantocleantech"}},{"@type":"WebPage","@id":"https:\/\/nantocleantech.us\/es\/empresa\/#webpage","url":"https:\/\/nantocleantech.us\/es\/empresa\/","name":"EMPRESA - Nanto Cleantech","description":"Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/nantocleantech.us\/es\/#website"},"breadcrumb":{"@id":"https:\/\/nantocleantech.us\/es\/empresa\/#breadcrumblist"},"author":{"@id":"https:\/\/nantocleantech.us\/es\/author\/nantocleantech\/#author"},"creator":{"@id":"https:\/\/nantocleantech.us\/es\/author\/nantocleantech\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/nantocleantech.us\/wp-content\/uploads\/2016\/07\/company-overview.jpg","@id":"https:\/\/nantocleantech.us\/es\/empresa\/#mainImage","width":750,"height":260},"primaryImageOfPage":{"@id":"https:\/\/nantocleantech.us\/es\/empresa\/#mainImage"},"datePublished":"2016-07-20T15:10:24+02:00","dateModified":"2018-09-17T16:40:36+02:00"},{"@type":"WebSite","@id":"https:\/\/nantocleantech.us\/es\/#website","url":"https:\/\/nantocleantech.us\/es\/","name":"Nanto Cleantech","description":"Singularity Materials","inLanguage":"es-ES","publisher":{"@id":"https:\/\/nantocleantech.us\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Nanto Cleantech - Singularity Materials","og:type":"article","og:title":"EMPRESA - Nanto Cleantech","og:description":"Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones","og:url":"https:\/\/nantocleantech.us\/es\/empresa\/","article:published_time":"2016-07-20T13:10:24+00:00","article:modified_time":"2018-09-17T14:40:36+00:00","twitter:card":"summary_large_image","twitter:title":"EMPRESA - Nanto Cleantech","twitter:description":"Nanto Cleantech es una empresa orientada hacia la innovaci\u00f3n, que posee el know-how, las patentes y las tecnolog\u00edas para realizar materiales avanzados de nueva generaci\u00f3n (anti-corrosi\u00f3n, flame\/fire retardant, anti stick etc.) destinados a la industria de los recubrimientos y de los pol\u00edmeros. La empresa perfecciona una variedad de soluciones para una amplia gama de aplicaciones"},"aioseo_meta_data":{"post_id":"11","title":null,"description":null,"keywords":[{"label":"nanto cleantech","value":"nanto cleantech"},{"label":"about us nanto cleantech","value":"about us nanto cleantech"},{"label":"company overview nanto cleantech","value":"company overview nanto cleantech"},{"label":"nanotechnology","value":"nanotechnology"},{"label":"advanced materials","value":"advanced materials"},{"label":"functional coatings","value":"functional coatings"},{"label":"proprietary nanotechnology","value":"proprietary nanotechnology"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-27 05:46:15","updated":"2025-06-27 10:46:38","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nantocleantech.us\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nantocleantech.us\/es\/category\/about-us\/\" title=\"About us\">About us<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEMPRESA\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nantocleantech.us\/es"},{"label":"About us","link":"https:\/\/nantocleantech.us\/es\/category\/about-us\/"},{"label":"EMPRESA","link":"https:\/\/nantocleantech.us\/es\/empresa\/"}],"jetpack_featured_media_url":"https:\/\/nantocleantech.us\/wp-content\/uploads\/2016\/07\/company-overview.jpg","_links":{"self":[{"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/posts\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":9,"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"predecessor-version":[{"id":849,"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/posts\/11\/revisions\/849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/media\/848"}],"wp:attachment":[{"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nantocleantech.us\/es\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}